{"id":756,"date":"2018-05-14T14:43:04","date_gmt":"2018-05-14T12:43:04","guid":{"rendered":"http:\/\/www.burgeap.fr\/?p=756"},"modified":"2019-04-12T17:49:21","modified_gmt":"2019-04-12T15:49:21","slug":"retrouvez-notre-experte-qualite-de-lair-lors-des-journees-atmosfair","status":"publish","type":"post","link":"https:\/\/www.ginger-burgeap.com\/en\/retrouvez-notre-experte-qualite-de-lair-lors-des-journees-atmosfair\/","title":{"rendered":"Retrouvez notre experte qualit\u00e9 de l&#8217;air lors des journ\u00e9es Atmos&#8217;Fair"},"content":{"rendered":"<p>Notre experte Sylvie Traverse intervient le 20 juin lors des journ\u00e9es\u00a0<a href=\"http:\/\/www.atmosfair.fr\/FICHIERS\/program.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Atmos&#8217;Fair,\u00a0<\/a>le congr\u00e8s annuel des acteurs de la qualit\u00e9 de l\u2019air dont le th\u00e8me cette ann\u00e9e est la pollution de l&#8217;air ext\u00e9rieur et int\u00e9rieur : sources, impacts, diagnostics &amp; solutions. Sylvie Traverse donnera une conf\u00e9rence le jeudi \u00e0 15h00 sur l&#8217;influence des conditions hydrom\u00e9t\u00e9orologiques sur l\u2019impact dans l\u2019air des pollutions volatiles pr\u00e9sentes dans les sols pour diff\u00e9rentes situations.<\/p>\n<p>Pour plus d&#8217;informations, contactez-nous sur\u00a0<a href=\"mailto:burgeap@burgeap.fr\" target=\"_blank\" rel=\"alternate noopener noreferrer\">burgeap@burgeap.fr<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Notre experte Sylvie Traverse intervient le 20 juin lors des journ\u00e9es\u00a0Atmos&#8217;Fair,\u00a0le congr\u00e8s annuel des acteurs de la qualit\u00e9 de l\u2019air dont le th\u00e8me cette ann\u00e9e est la pollution de l&#8217;air ext\u00e9rieur et int\u00e9rieur : sources, impacts, diagnostics &amp; solutions. Sylvie Traverse donnera une conf\u00e9rence le jeudi \u00e0 15h00 sur l&#8217;influence des conditions hydrom\u00e9t\u00e9orologiques sur l\u2019impact dans l\u2019air des pollutions volatiles &#8230;<\/p>\n","protected":false},"author":2,"featured_media":757,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[947,5],"tags":[],"class_list":["post-756","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actu","category-non-classifiee"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Retrouvez notre experte qualit\u00e9 de l&#039;air lors des journ\u00e9es Atmos&#039;Fair - Burgeap<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ginger-burgeap.com\/en\/retrouvez-notre-experte-qualite-de-lair-lors-des-journees-atmosfair\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Retrouvez notre experte qualit\u00e9 de l&#039;air lors des journ\u00e9es Atmos&#039;Fair\" \/>\n<meta property=\"og:description\" content=\"Notre experte Sylvie Traverse intervient le 20 juin lors des journ\u00e9es\u00a0Atmos&#8217;Fair,\u00a0le congr\u00e8s annuel des acteurs de la qualit\u00e9 de l\u2019air dont le th\u00e8me cette ann\u00e9e est la pollution de l&#8217;air ext\u00e9rieur et int\u00e9rieur : sources, impacts, diagnostics &amp; solutions. Sylvie Traverse donnera une conf\u00e9rence le jeudi \u00e0 15h00 sur l&#8217;influence des conditions hydrom\u00e9t\u00e9orologiques sur l\u2019impact dans l\u2019air des pollutions volatiles ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ginger-burgeap.com\/en\/retrouvez-notre-experte-qualite-de-lair-lors-des-journees-atmosfair\/\" \/>\n<meta property=\"og:site_name\" content=\"Burgeap\" \/>\n<meta property=\"article:published_time\" content=\"2018-05-14T12:43:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-04-12T15:49:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ginger-burgeap.com\/wp-content\/uploads\/2018\/10\/atmosfair_2018.png\" \/>\n\t<meta property=\"og:image:width\" content=\"976\" \/>\n\t<meta property=\"og:image:height\" content=\"317\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Magali Malfugeon\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Magali Malfugeon\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ginger-burgeap.com\\\/en\\\/retrouvez-notre-experte-qualite-de-lair-lors-des-journees-atmosfair\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ginger-burgeap.com\\\/en\\\/retrouvez-notre-experte-qualite-de-lair-lors-des-journees-atmosfair\\\/\"},\"author\":{\"name\":\"Magali Malfugeon\",\"@id\":\"https:\\\/\\\/www.ginger-burgeap.com\\\/en\\\/#\\\/schema\\\/person\\\/fbbbf12e9b4f3518d5730dcddf77a670\"},\"headline\":\"Retrouvez notre experte qualit\u00e9 de l&#8217;air lors des journ\u00e9es Atmos&#8217;Fair\",\"datePublished\":\"2018-05-14T12:43:04+00:00\",\"dateModified\":\"2019-04-12T15:49:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ginger-burgeap.com\\\/en\\\/retrouvez-notre-experte-qualite-de-lair-lors-des-journees-atmosfair\\\/\"},\"wordCount\":99,\"image\":{\"@id\":\"https:\\\/\\\/www.ginger-burgeap.com\\\/en\\\/retrouvez-notre-experte-qualite-de-lair-lors-des-journees-atmosfair\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ginger-burgeap.com\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/atmosfair_2018.png\",\"articleSection\":[\"actualit\u00e9s\",\"Non classifi\u00e9(e)\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ginger-burgeap.com\\\/en\\\/retrouvez-notre-experte-qualite-de-lair-lors-des-journees-atmosfair\\\/\",\"url\":\"https:\\\/\\\/www.ginger-burgeap.com\\\/en\\\/retrouvez-notre-experte-qualite-de-lair-lors-des-journees-atmosfair\\\/\",\"name\":\"Retrouvez notre experte qualit\u00e9 de l'air lors des journ\u00e9es Atmos'Fair - Burgeap\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ginger-burgeap.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ginger-burgeap.com\\\/en\\\/retrouvez-notre-experte-qualite-de-lair-lors-des-journees-atmosfair\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ginger-burgeap.com\\\/en\\\/retrouvez-notre-experte-qualite-de-lair-lors-des-journees-atmosfair\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ginger-burgeap.com\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/atmosfair_2018.png\",\"datePublished\":\"2018-05-14T12:43:04+00:00\",\"dateModified\":\"2019-04-12T15:49:21+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.ginger-burgeap.com\\\/en\\\/#\\\/schema\\\/person\\\/fbbbf12e9b4f3518d5730dcddf77a670\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ginger-burgeap.com\\\/en\\\/retrouvez-notre-experte-qualite-de-lair-lors-des-journees-atmosfair\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ginger-burgeap.com\\\/en\\\/retrouvez-notre-experte-qualite-de-lair-lors-des-journees-atmosfair\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.ginger-burgeap.com\\\/en\\\/retrouvez-notre-experte-qualite-de-lair-lors-des-journees-atmosfair\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ginger-burgeap.com\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/atmosfair_2018.png\",\"contentUrl\":\"https:\\\/\\\/www.ginger-burgeap.com\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/atmosfair_2018.png\",\"width\":976,\"height\":317},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ginger-burgeap.com\\\/en\\\/retrouvez-notre-experte-qualite-de-lair-lors-des-journees-atmosfair\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.ginger-burgeap.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Retrouvez notre experte qualit\u00e9 de l&#8217;air lors des journ\u00e9es Atmos&#8217;Fair\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ginger-burgeap.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.ginger-burgeap.com\\\/en\\\/\",\"name\":\"Burgeap\",\"description\":\"Bureau d&#039;\u00e9tudes sp\u00e9cialis\u00e9 en environnement\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ginger-burgeap.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ginger-burgeap.com\\\/en\\\/#\\\/schema\\\/person\\\/fbbbf12e9b4f3518d5730dcddf77a670\",\"name\":\"Magali Malfugeon\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7343ffc75c8910f6a297490aa13006b434703f69930f9e45cbc7818dc5700ee6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7343ffc75c8910f6a297490aa13006b434703f69930f9e45cbc7818dc5700ee6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7343ffc75c8910f6a297490aa13006b434703f69930f9e45cbc7818dc5700ee6?s=96&d=mm&r=g\",\"caption\":\"Magali Malfugeon\"},\"url\":\"https:\\\/\\\/www.ginger-burgeap.com\\\/en\\\/author\\\/magali_malfugeon\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Retrouvez notre experte qualit\u00e9 de l'air lors des journ\u00e9es Atmos'Fair - Burgeap","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ginger-burgeap.com\/en\/retrouvez-notre-experte-qualite-de-lair-lors-des-journees-atmosfair\/","og_locale":"en_US","og_type":"article","og_title":"Retrouvez notre experte qualit\u00e9 de l'air lors des journ\u00e9es Atmos'Fair","og_description":"Notre experte Sylvie Traverse intervient le 20 juin lors des journ\u00e9es\u00a0Atmos&#8217;Fair,\u00a0le congr\u00e8s annuel des acteurs de la qualit\u00e9 de l\u2019air dont le th\u00e8me cette ann\u00e9e est la pollution de l&#8217;air ext\u00e9rieur et int\u00e9rieur : sources, impacts, diagnostics &amp; solutions. Sylvie Traverse donnera une conf\u00e9rence le jeudi \u00e0 15h00 sur l&#8217;influence des conditions hydrom\u00e9t\u00e9orologiques sur l\u2019impact dans l\u2019air des pollutions volatiles ...","og_url":"https:\/\/www.ginger-burgeap.com\/en\/retrouvez-notre-experte-qualite-de-lair-lors-des-journees-atmosfair\/","og_site_name":"Burgeap","article_published_time":"2018-05-14T12:43:04+00:00","article_modified_time":"2019-04-12T15:49:21+00:00","og_image":[{"width":976,"height":317,"url":"https:\/\/www.ginger-burgeap.com\/wp-content\/uploads\/2018\/10\/atmosfair_2018.png","type":"image\/png"}],"author":"Magali Malfugeon","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Magali Malfugeon"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ginger-burgeap.com\/en\/retrouvez-notre-experte-qualite-de-lair-lors-des-journees-atmosfair\/#article","isPartOf":{"@id":"https:\/\/www.ginger-burgeap.com\/en\/retrouvez-notre-experte-qualite-de-lair-lors-des-journees-atmosfair\/"},"author":{"name":"Magali Malfugeon","@id":"https:\/\/www.ginger-burgeap.com\/en\/#\/schema\/person\/fbbbf12e9b4f3518d5730dcddf77a670"},"headline":"Retrouvez notre experte qualit\u00e9 de l&#8217;air lors des journ\u00e9es Atmos&#8217;Fair","datePublished":"2018-05-14T12:43:04+00:00","dateModified":"2019-04-12T15:49:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ginger-burgeap.com\/en\/retrouvez-notre-experte-qualite-de-lair-lors-des-journees-atmosfair\/"},"wordCount":99,"image":{"@id":"https:\/\/www.ginger-burgeap.com\/en\/retrouvez-notre-experte-qualite-de-lair-lors-des-journees-atmosfair\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ginger-burgeap.com\/wp-content\/uploads\/2018\/10\/atmosfair_2018.png","articleSection":["actualit\u00e9s","Non classifi\u00e9(e)"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.ginger-burgeap.com\/en\/retrouvez-notre-experte-qualite-de-lair-lors-des-journees-atmosfair\/","url":"https:\/\/www.ginger-burgeap.com\/en\/retrouvez-notre-experte-qualite-de-lair-lors-des-journees-atmosfair\/","name":"Retrouvez notre experte qualit\u00e9 de l'air lors des journ\u00e9es Atmos'Fair - Burgeap","isPartOf":{"@id":"https:\/\/www.ginger-burgeap.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ginger-burgeap.com\/en\/retrouvez-notre-experte-qualite-de-lair-lors-des-journees-atmosfair\/#primaryimage"},"image":{"@id":"https:\/\/www.ginger-burgeap.com\/en\/retrouvez-notre-experte-qualite-de-lair-lors-des-journees-atmosfair\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ginger-burgeap.com\/wp-content\/uploads\/2018\/10\/atmosfair_2018.png","datePublished":"2018-05-14T12:43:04+00:00","dateModified":"2019-04-12T15:49:21+00:00","author":{"@id":"https:\/\/www.ginger-burgeap.com\/en\/#\/schema\/person\/fbbbf12e9b4f3518d5730dcddf77a670"},"breadcrumb":{"@id":"https:\/\/www.ginger-burgeap.com\/en\/retrouvez-notre-experte-qualite-de-lair-lors-des-journees-atmosfair\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ginger-burgeap.com\/en\/retrouvez-notre-experte-qualite-de-lair-lors-des-journees-atmosfair\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.ginger-burgeap.com\/en\/retrouvez-notre-experte-qualite-de-lair-lors-des-journees-atmosfair\/#primaryimage","url":"https:\/\/www.ginger-burgeap.com\/wp-content\/uploads\/2018\/10\/atmosfair_2018.png","contentUrl":"https:\/\/www.ginger-burgeap.com\/wp-content\/uploads\/2018\/10\/atmosfair_2018.png","width":976,"height":317},{"@type":"BreadcrumbList","@id":"https:\/\/www.ginger-burgeap.com\/en\/retrouvez-notre-experte-qualite-de-lair-lors-des-journees-atmosfair\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ginger-burgeap.com\/en\/"},{"@type":"ListItem","position":2,"name":"Retrouvez notre experte qualit\u00e9 de l&#8217;air lors des journ\u00e9es Atmos&#8217;Fair"}]},{"@type":"WebSite","@id":"https:\/\/www.ginger-burgeap.com\/en\/#website","url":"https:\/\/www.ginger-burgeap.com\/en\/","name":"Burgeap","description":"Bureau d&#039;\u00e9tudes sp\u00e9cialis\u00e9 en environnement","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ginger-burgeap.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.ginger-burgeap.com\/en\/#\/schema\/person\/fbbbf12e9b4f3518d5730dcddf77a670","name":"Magali Malfugeon","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/7343ffc75c8910f6a297490aa13006b434703f69930f9e45cbc7818dc5700ee6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7343ffc75c8910f6a297490aa13006b434703f69930f9e45cbc7818dc5700ee6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7343ffc75c8910f6a297490aa13006b434703f69930f9e45cbc7818dc5700ee6?s=96&d=mm&r=g","caption":"Magali Malfugeon"},"url":"https:\/\/www.ginger-burgeap.com\/en\/author\/magali_malfugeon\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ginger-burgeap.com\/en\/wp-json\/wp\/v2\/posts\/756","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ginger-burgeap.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ginger-burgeap.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ginger-burgeap.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ginger-burgeap.com\/en\/wp-json\/wp\/v2\/comments?post=756"}],"version-history":[{"count":1,"href":"https:\/\/www.ginger-burgeap.com\/en\/wp-json\/wp\/v2\/posts\/756\/revisions"}],"predecessor-version":[{"id":758,"href":"https:\/\/www.ginger-burgeap.com\/en\/wp-json\/wp\/v2\/posts\/756\/revisions\/758"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ginger-burgeap.com\/en\/wp-json\/wp\/v2\/media\/757"}],"wp:attachment":[{"href":"https:\/\/www.ginger-burgeap.com\/en\/wp-json\/wp\/v2\/media?parent=756"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ginger-burgeap.com\/en\/wp-json\/wp\/v2\/categories?post=756"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ginger-burgeap.com\/en\/wp-json\/wp\/v2\/tags?post=756"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}